{"id":77,"date":"2014-01-25T14:48:13","date_gmt":"2014-01-25T12:48:13","guid":{"rendered":"http:\/\/31ppp.de\/bianca-noeth\/?p=77"},"modified":"2014-07-27T19:52:20","modified_gmt":"2014-07-27T17:52:20","slug":"das-gespraech-mit-dem-patenabgeordneten","status":"publish","type":"post","link":"https:\/\/31ppp.de\/bianca-noeth\/2014\/01\/25\/das-gespraech-mit-dem-patenabgeordneten\/","title":{"rendered":"Das Gespr\u00e4ch mit dem Patenabgeordneten"},"content":{"rendered":"<p>Am 13.Januar 2014 hatte dann das lange Warten endlich ein Ende, nachdem ich eine E-Mail von der Assistentin meines MdBs erhalten habe. Hierin war zu lesen <em>&#8220;Die Austauschorganisation GIZ hat Sie Herrn Dr. Riesenhuber &#8211; gemeinsam mit zwei weiteren Bewerberinnen &#8211; f\u00fcr die Endauswahl um das Stipendium des Parlamentarischen-Patenschafts-Programms vorgeschlagen.&#8221; <\/em>Ich freute mich riesig und best\u00e4tigte gleich den Termin.<\/p>\n<p>Am 21.Januar 2014 hatte ich dann das alles entscheidende Gespr\u00e4ch mit Herrn Prof. Dr. Heinz Riesenhuber (CDU). Ich war total aufgeregt aber auch sehr gespannt den Alterspr\u00e4sidenten des Deutschen Bundestages pers\u00f6nlich kennenzulernen, nicht zu vergessen, war mir bewusst, dass dies das alles entscheidende Gespr\u00e4ch f\u00fcr mich werden w\u00fcrde.<\/p>\n<p>Schnell wurde noch ein Selfie geschossen, f\u00fcr die diejenigen, die sich fragen, was man zu so einem Gespr\u00e4ch anzieht \ud83d\ude1b und los ging es in das B\u00fcro des MdBs.<\/p>\n<p><a href=\"http:\/\/31ppp.de\/bianca-noeth\/wp-content\/uploads\/sites\/32\/2014\/01\/IMG_1628-e1406482403341.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-85 aligncenter\" src=\"http:\/\/31ppp.de\/bianca-noeth\/wp-content\/uploads\/sites\/32\/2014\/01\/IMG_1628-e1406482403341-225x300.jpg\" alt=\"IMG_1628\" width=\"284\" height=\"378\" srcset=\"https:\/\/31ppp.de\/bianca-noeth\/wp-content\/uploads\/sites\/32\/2014\/01\/IMG_1628-e1406482403341-225x300.jpg 225w, https:\/\/31ppp.de\/bianca-noeth\/wp-content\/uploads\/sites\/32\/2014\/01\/IMG_1628-e1406482403341-768x1024.jpg 768w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" \/><\/a><\/p>\n<p>Meine Oma hat mir netterweise den Gl\u00fccksbringer meiner Uroma \u00fcberlassen, was mich ein wenig beruhigte.<\/p>\n<p><a href=\"http:\/\/31ppp.de\/bianca-noeth\/wp-content\/uploads\/sites\/32\/2014\/01\/IMG_1632.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-84 size-medium\" src=\"http:\/\/31ppp.de\/bianca-noeth\/wp-content\/uploads\/sites\/32\/2014\/01\/IMG_1632-e1406482498482-300x300.jpg\" alt=\"IMG_1632\" width=\"300\" height=\"300\" srcset=\"https:\/\/31ppp.de\/bianca-noeth\/wp-content\/uploads\/sites\/32\/2014\/01\/IMG_1632-e1406482498482-300x300.jpg 300w, https:\/\/31ppp.de\/bianca-noeth\/wp-content\/uploads\/sites\/32\/2014\/01\/IMG_1632-e1406482498482-150x150.jpg 150w, https:\/\/31ppp.de\/bianca-noeth\/wp-content\/uploads\/sites\/32\/2014\/01\/IMG_1632-e1406482498482-1024x1024.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Es war ein sehr nettes und interessantes Gespr\u00e4ch, was leider auch ziemlich schnell endete, da ja noch zwei weitere Kandidatinnen ihr Gespr\u00e4ch an diesem Tag hatten. Anschlie\u00dfend bedankte ich mich f\u00fcr das freundliche Gespr\u00e4ch und machte mich, mit dem Gedanken, dass ich nur noch eine Entscheidung von meinem Traum entfernt war, auf den Weg nach Hause. Wo dann das lange Zittern auf die entg\u00fcltige Entscheidung ob ich das Stipendium bekommen w\u00fcrde oder nicht, begann.<\/p>\n<p>Ein gro\u00dfer Dank geht auch nochmal an alle meine Liebsten, die mir so gut zugesprochen haben \ud83d\ude42 Ihr seid wirklich die Besten!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 13.Januar 2014 hatte dann das lange Warten endlich ein Ende, nachdem ich eine E-Mail von der Assistentin meines MdBs erhalten habe. Hierin war zu lesen &#8220;Die Austauschorganisation GIZ hat Sie Herrn Dr. Riesenhuber &#8211; gemeinsam mit zwei weiteren Bewerberinnen &#8211; f\u00fcr die Endauswahl um das Stipendium des Parlamentarischen-Patenschafts-Programms vorgeschlagen.&#8221; Ich freute mich riesig und best\u00e4tigte gleich den Termin. Am 21.Januar 2014 hatte ich dann das alles entscheidende Gespr\u00e4ch mit Herrn Prof. Dr. Heinz Riesenhuber (CDU). Ich war total aufgeregt aber auch sehr gespannt den Alterspr\u00e4sidenten des Deutschen Bundestages pers\u00f6nlich&#8230;<a class=\"read-more\" href=\"https:\/\/31ppp.de\/bianca-noeth\/2014\/01\/25\/das-gespraech-mit-dem-patenabgeordneten\/\">read more<\/a><\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-77","post","type-post","status-publish","format-standard","hentry","category-allgemein","et-no-image","et-bg-layout-dark"],"_links":{"self":[{"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/posts\/77","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/comments?post=77"}],"version-history":[{"count":6,"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/posts\/77\/revisions"}],"predecessor-version":[{"id":93,"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/posts\/77\/revisions\/93"}],"wp:attachment":[{"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/media?parent=77"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/categories?post=77"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/31ppp.de\/bianca-noeth\/wp-json\/wp\/v2\/tags?post=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}